{"id":80027,"date":"2024-09-24T09:14:02","date_gmt":"2024-09-24T15:14:02","guid":{"rendered":"http:\/\/mickyandoniehn.com\/radio\/2024\/09\/24\/john-sube-a-huracan-categoria-3-y-toca-el-sur-de-mexico\/"},"modified":"2024-09-24T09:14:02","modified_gmt":"2024-09-24T15:14:02","slug":"john-sube-a-huracan-categoria-3-y-toca-el-sur-de-mexico","status":"publish","type":"post","link":"https:\/\/mickyandoniehn.com\/radio\/2024\/09\/24\/john-sube-a-huracan-categoria-3-y-toca-el-sur-de-mexico\/","title":{"rendered":"John sube a hurac\u00e1n categor\u00eda 3 y toca el sur de M\u00e9xico"},"content":{"rendered":"<\/p>\n<p>El cicl\u00f3n John, hurac\u00e1n de categor\u00eda 3 en la escala de Saffir-Simpson, toc\u00f3 tierra este lunes por la noche en el estado mexicano de Guerrero, sur del pa\u00eds, inform\u00f3 el Servicio Meteorol\u00f3gico Nacional (SMN).<\/p>\n<p>\u00abEl centro del hurac\u00e1n John, de categor\u00eda 3, toc\u00f3 tierra a las 21:15 hora local (03:15 GMT del martes) al sur-suroeste de Marquelia, estado de Guerrero, con vientos de 195 kil\u00f3metros por hora (km\/h) y rachas 220 km\u00bb, precis\u00f3 el SMN.<\/p>\n<p>En su reporte mas reciente, el organismo preciso que a las 21:30 hora local (03:30 GMT del martes) el cicl\u00f3n, d\u00e9cimo de la temporada del Pac\u00edfico y el segundo que pasa sobre territorio mexicano, se localizaba en tierra, a 10 kil\u00f3metros (km) al este de Copala y a 40 km al noroeste de Punta Maldonado, ambios lugares en el estado de Guerrero.<\/p>\n<p>El golpe de John llega al estado de Guerrro luego de que en octubre de 2023 el balneario de Acapulco sufri\u00f3 el paso del hurac\u00e1n Otis, que fue el cicl\u00f3n m\u00e1s fuerte de la pasada temporada, que toc\u00f3 tierra el 25 de octubre como hurac\u00e1n de categor\u00eda 5, con vientos sostenidos de 260 km\/hora, causando al menos 51 muertos y 34 desaparecidos, y p\u00e9rdidas de unos 3.200 millones de d\u00f3lares.<\/p>\n<p>Esta noche, al entrar a territorio, John present\u00f3 vientos sostenidos de 195 km\/h y rachas de 220 km\/h y ahora se desplaza hacia el norte.<\/p>\n<p>El reporte apunt\u00f3 que la amplia circulaci\u00f3n de John generar\u00e1 lluvias puntuales extraordinarias (superiores a 250 mm) en Oaxaca y Guerrero, y lluvias puntuales torrenciales (150 a 250 mm) en Chiapas.<\/p>\n<p>Adem\u00e1s de lluvias puntuales intensas (75 a 150 mm) en Veracruz y Puebla; lluvias puntuales muy fuertes (50 a 75 mm) en Tabasco; y avis\u00f3 que las bandas nubosas de John reforzar\u00e1n la probabilidad de lluvias fuertes a muy fuertes en el centro del pa\u00eds, incluido el valle de M\u00e9xico.<\/p>\n<\/p>\n<p>Tambi\u00e9n pronostic\u00f3 viento con rachas de 200 a 220 km\/h y oleaje de 5 a 7 metros de altura en el occidente de Oaxaca y oriente de Guerrero.<\/p>\n<p>Debido a esas condiciones, el SMN mantiene una zona de prevenci\u00f3n por efectos de hurac\u00e1n desde el este de Acapulco, Guerrero, hasta Bah\u00edas de Huatulco, Oaxaca, y zona de prevenci\u00f3n por efectos de tormenta tropical desde el este de Bah\u00edas de Huatulco hasta Salina Cruz, Oaxaca.<\/p>\n<p>El Meteorol\u00f3gico de M\u00e9xico pidi\u00f3 a la poblaci\u00f3n extremar precauciones, lo que incluy\u00f3 a la navegaci\u00f3n mar\u00edtima, as\u00ed como atender las recomendaciones emitidas por las autoridades de Protecci\u00f3n Civil.<\/p>\n<p>El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, advirti\u00f3 este lunes por la noche que el hurac\u00e1n John tocar\u00eda tierra como hurac\u00e1n de categor\u00eda 3 en el sur de M\u00e9xico.<\/p>\n<p>\u00abAtento aviso a toda la gente de la Costa Chica de Guerrero y de Cuajinicuilapa a Huatulco: el hurac\u00e1n John tocar\u00e1 tierra en dos horas con categor\u00eda 3\u00bb, apunt\u00f3 el mandatario en un mensaje en redes sociales que public\u00f3 alrededor de las 20:00 hora local(02:00 GMT del martes).<\/p>\n<p>\u00abBusquen las partes altas, prot\u00e9janse y no olviden que lo m\u00e1s importante es la vida; lo material se repone. Estaremos pendientes\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>En Guerrero, la titular de Protecci\u00f3n Civil, Laura Vel\u00e1zquez, y la Gobernadora del estado, Evelyn Salgado, junto con autoridades militares informaron que estaban preparados para el despliegue del Plan DN-III, ante desastres naturales con agentes del Ej\u00e9rcito, Marina y Guardia Nacional en los municipios de Cuajinicuilapa, Copala, Florencio Villarreal y Marquelia, en la regi\u00f3n de la Costa Chica de Guerrero, donde se abrieron 299 refugios para la poblaci\u00f3n en peligro.<\/p>\n<p>Adem\u00e1s, este lunes, autoridades de los estados de Oaxaca y Guerrero decidieron suspender las clases en todos los niveles esclares ante impacto de John.<\/p>\n<p>La semana pasada la tormenta Ileana azot\u00f3 el estado de Sinaloa, en el noroeste del pa\u00eds, donde dej\u00f3 da\u00f1os menores, mientras que tres ciclones han golpeado a M\u00e9xico por el Atl\u00e1ntico: el hurac\u00e1n Beryl y la tormenta Chris, que dejaron saldo blanco en julio, y la tormenta Alberto en junio, cuando dej\u00f3 seis muertos en Nuevo Le\u00f3n, estado de la frontera norte de M\u00e9xico.<\/p>\n<p>Las autoridades mexicanas pronosticaron en mayo hasta 41 ciclones con nombre en el oc\u00e9ano Atl\u00e1ntico y el Pac\u00edfico, de los que al menos cinco golpear\u00edan el pa\u00eds.<\/p>\n<p>Fuente: Hondudiario<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cicl\u00f3n John, hurac\u00e1n de categor\u00eda 3 en la escala de Saffir-Simpson, toc\u00f3 tierra este lunes por la noche en el estado mexicano de Guerrero, sur del pa\u00eds, inform\u00f3 el Servicio Meteorol\u00f3gico Nacional (SMN). \u00abEl centro del hurac\u00e1n John, de categor\u00eda 3, toc\u00f3 tierra a las 21:15 hora local (03:15 GMT del martes) al sur-suroeste &hellip;<\/p>\n","protected":false},"author":0,"featured_media":80028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-80027","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-noticias"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/mickyandoniehn.com\/radio\/wp-content\/uploads\/2024\/09\/7-7-k62oJ9.jpeg","_links":{"self":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/80027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/comments?post=80027"}],"version-history":[{"count":0,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/80027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media\/80028"}],"wp:attachment":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media?parent=80027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/categories?post=80027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/tags?post=80027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}