{"id":79930,"date":"2024-09-19T13:12:33","date_gmt":"2024-09-19T19:12:33","guid":{"rendered":"http:\/\/mickyandoniehn.com\/radio\/2024\/09\/19\/manana-ingresan-1-6-millones-de-moscas-para-combate-de-gusano-barrenador\/"},"modified":"2024-09-19T13:12:33","modified_gmt":"2024-09-19T19:12:33","slug":"manana-ingresan-1-6-millones-de-moscas-para-combate-de-gusano-barrenador","status":"publish","type":"post","link":"https:\/\/mickyandoniehn.com\/radio\/2024\/09\/19\/manana-ingresan-1-6-millones-de-moscas-para-combate-de-gusano-barrenador\/","title":{"rendered":"Ma\u00f1ana ingresan 1.6 millones de moscas para combate de gusano barrenador"},"content":{"rendered":"<p><strong><br \/>\n19.09.2024<\/strong><\/p>\n<p><strong>Tegucigalpa \u2013<\/strong>\u00a0El director del Organismo Internacional Regional de Sanidad Agropecuaria (Oirsa),\u00a0<strong>Ra\u00fal Rodas<\/strong>\u00a0inform\u00f3 que ma\u00f1ana viernes ingresar\u00e1 al pa\u00eds v\u00eda Palmerola con procedencia de Panam\u00e1, un lote de un mill\u00f3n 600 mil moscas esterilizadas para combatir el gusano barrenador.<\/p>\n<p>El funcionario explic\u00f3 que las moscas se liberan en las zonas donde est\u00e1 detectada la plaga de gusano barrenador causado por mosca de t\u00f3rsalo, con el objetivo de que el insecto macho esterilizado se aparee con la mosca f\u00e9rtiles presentes en el pa\u00eds.<\/p>\n<p>\u201cEsto impide que se d\u00e9 la siguiente generaci\u00f3n filial en el pa\u00eds y as\u00ed, paso a paso y en un horizonte de tiempo que puede demorar un poco, vamos a ir erradicando los brotes que han sido detectados en Honduras\u201d, detall\u00f3.<\/p>\n<p>Los insectos voladores arriban al pa\u00eds alrededor del mediod\u00eda y luego los t\u00e9cnicos del Servicio Nacional de Sanidad e Inocuidad Agroalimentaria (Senasa) realizan el proceso de liberaci\u00f3n en las zonas donde se ha detectado la plaga, como una medida de control y erradicaci\u00f3n.<\/p>\n<p>Este ingreso de moscas esterilizadas forma parte de un primer lote que ser\u00e1 introducido, ya que dependiendo del comportamiento de la plaga se proceder\u00e1 a m\u00e1s importaciones, seg\u00fan lo indicado por Rodas.<\/p>\n<p>En las \u00faltimas horas, las autoridades de Senasa, informaron que detectaron<strong><a href=\"https:\/\/proceso.hn\/detectan-cuatro-nuevos-casos-de-gusano-barrenador-en-honduras\/\"> cuatro nuevos casos<\/a><\/strong> de ganado infectado con el gusano barrenador, con lo que suman ocho casos en Honduras.<\/p>\n<p>Los casos est\u00e1n distribuidos, siete en el departamento de Choluteca y uno en Olancho.<\/p>\n<p>El gusano barrenador es una enfermedad causada por las larvas de la mosca Cochliomyia hominivorax (Coquerel) que deposita sus huevos en cualquier herida abierta de un animal de sangre caliente, incluyendo a las personas, horas despu\u00e9s de que se han depositado, nacen los gusanos los cuales se alimentan del tejido vivo.<\/p>\n<p>Las larvas son de color blanco cremoso, al madurar adquieren un tinte rojizo, est\u00e1n en posici\u00f3n vertical y enterradas profundamente en los tejidos, tienen ganchos y espinas, se mueven barrenando hacia el centro de los tejidos y su presencia puede provocar infecciones secundarias por organismos contaminantes.<\/p>\n<p>Fuente: Proceso.hn<\/p>\n","protected":false},"excerpt":{"rendered":"<p>19.09.2024 Tegucigalpa \u2013\u00a0El director del Organismo Internacional Regional de Sanidad Agropecuaria (Oirsa),\u00a0Ra\u00fal Rodas\u00a0inform\u00f3 que ma\u00f1ana viernes ingresar\u00e1 al pa\u00eds v\u00eda Palmerola con procedencia de Panam\u00e1, un lote de un mill\u00f3n 600 mil moscas esterilizadas para combatir el gusano barrenador. El funcionario explic\u00f3 que las moscas se liberan en las zonas donde est\u00e1 detectada la plaga &hellip;<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-79930","post","type-post","status-publish","format-standard","","category-noticias"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/79930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/comments?post=79930"}],"version-history":[{"count":0,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/79930\/revisions"}],"wp:attachment":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media?parent=79930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/categories?post=79930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/tags?post=79930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}