{"id":79793,"date":"2024-09-11T10:13:41","date_gmt":"2024-09-11T16:13:41","guid":{"rendered":"http:\/\/mickyandoniehn.com\/radio\/2024\/09\/11\/economista-senala-que-para-saber-si-se-justifica-aumento-al-presupuesto-2025-primero-debe-analizarse-como-se-esta-ejecutando-el-vigente\/"},"modified":"2024-09-11T10:13:41","modified_gmt":"2024-09-11T16:13:41","slug":"economista-senala-que-para-saber-si-se-justifica-aumento-al-presupuesto-2025-primero-debe-analizarse-como-se-esta-ejecutando-el-vigente","status":"publish","type":"post","link":"https:\/\/mickyandoniehn.com\/radio\/2024\/09\/11\/economista-senala-que-para-saber-si-se-justifica-aumento-al-presupuesto-2025-primero-debe-analizarse-como-se-esta-ejecutando-el-vigente\/","title":{"rendered":"Economista se\u00f1ala que para saber si se justifica aumento al presupuesto 2025, primero debe analizarse c\u00f3mo se est\u00e1 ejecutando el vigente"},"content":{"rendered":"<\/p>\n<p><strong>Tegucigalpa \u2013\u00a0<\/strong>El economistaMario Sosa\u00a0expres\u00f3 sus dudas de que la ejecuci\u00f3n presupuestaria para este a\u00f1o llegue a 98 % como la reportada el a\u00f1o pasado por las autoridades econ\u00f3micas.<\/p>\n<p>Para determinar si se justifica el incremento de un 5.8 % al presupuesto 2025 aprobado en las \u00faltimas horas, el economista se\u00f1al\u00f3 que primero se debe ver c\u00f3mo se est\u00e1 ejecutando el presupuesto vigente.<\/p>\n<p>El anteproyecto de Presupuesto General de la Rep\u00fablica para el a\u00f1o 2025 aprobado anoche asciende a 430 mil 907.8 millones de lempiras, 23 mil millones m\u00e1s que en 2024, un aumento del 5.8 %.<\/p>\n<p>\u201cHay que recordar que el a\u00f1o pasado (en 2023) se lleg\u00f3 a un 98 % de la ejecuci\u00f3n y ahorita estamos esperando que se pase del 98 % para saber si se pudo desembolsar todos esos fondos en educaci\u00f3n, salud, en todo lo que va orientado el presupuesto\u201d, detall\u00f3.<\/p>\n<p>Sosa dijo que en la actualidad se est\u00e1n viendo problem\u00e1ticas tanto en la parte de energ\u00eda y \u201cmiramos que si realmente se est\u00e1 ejecutando o se va a ejecutar en este caso para el pr\u00f3ximo a\u00f1o 2025 estamos esperando que sea haga un 100 %, lastimosamente todo queda en papel\u201d.<\/p>\n<p>\u201cYo realmente no creo que sea a un 98 % como la del a\u00f1o pasado, creo que pudimos haber llegado a un 60 % y todo esto se va en capital humano\u201d, dijo al agregar que ese nivel de ejecuci\u00f3n presupuestaria no considera un desarrollo como pa\u00eds.<\/p>\n<p>Adem\u00e1s, refiri\u00f3 que debe considerarse que el Fondo Monetario Internacional (FMI) debe identificar si la aprobaci\u00f3n del presupuesto se va a generar y mencion\u00f3 que el pa\u00eds ha tenido problemas de riesgo pa\u00eds porque se ha incrementado esta situaci\u00f3n con la inversi\u00f3n extranjera.<\/p>\n<p>\u00a0<\/p>\n<p>Fuente: Proceso Digital<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tegucigalpa \u2013\u00a0El economistaMario Sosa\u00a0expres\u00f3 sus dudas de que la ejecuci\u00f3n presupuestaria para este a\u00f1o llegue a 98 % como la reportada el a\u00f1o pasado por las autoridades econ\u00f3micas. Para determinar si se justifica el incremento de un 5.8 % al presupuesto 2025 aprobado en las \u00faltimas horas, el economista se\u00f1al\u00f3 que primero se debe ver &hellip;<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-79793","post","type-post","status-publish","format-standard","","category-noticias"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/79793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/comments?post=79793"}],"version-history":[{"count":0,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/79793\/revisions"}],"wp:attachment":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media?parent=79793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/categories?post=79793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/tags?post=79793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}