{"id":79249,"date":"2024-09-06T15:12:35","date_gmt":"2024-09-06T21:12:35","guid":{"rendered":"http:\/\/mickyandoniehn.com\/radio\/2024\/09\/06\/uno-de-cada-cinco-ninos-en-el-mundo-tiene-sobrepeso-u-obesidad-2\/"},"modified":"2024-09-06T15:12:35","modified_gmt":"2024-09-06T21:12:35","slug":"uno-de-cada-cinco-ninos-en-el-mundo-tiene-sobrepeso-u-obesidad-2","status":"publish","type":"post","link":"https:\/\/mickyandoniehn.com\/radio\/2024\/09\/06\/uno-de-cada-cinco-ninos-en-el-mundo-tiene-sobrepeso-u-obesidad-2\/","title":{"rendered":"Uno de cada cinco ni\u00f1os en el mundo tiene sobrepeso u obesidad"},"content":{"rendered":"<\/p>\n<p>06.09.2024<\/p>\n<p>El\u00a0sobrepeso\u00a0y la\u00a0obesidad\u00a0en la infancia y la adolescencia representan un problema de salud global, asociado a consecuencias adversas a lo largo de la vida. Debido a esto, la Dra. Xinyue Zhang de la\u00a0Universidad de Sichuan\u00a0en China, junto con colaboradores de otras instituciones del pa\u00eds, estimaron la prevalencia mundial de sobrepeso y obesidad en ni\u00f1os y adolescentes, y evaluaron los posibles factores de riesgo y comorbilidades.<\/p>\n<p>Realizaron un metaan\u00e1lisis mediante b\u00fasquedas sistem\u00e1ticas en las bases de datos MEDLINE, Web of Science, Embase y Cochrane. Los art\u00edculos seleccionados inclu\u00edan a participantes menores de 18 a\u00f1os con informaci\u00f3n sobre el\u00a0\u00edndice de masa corporal (IMC).<\/p>\n<p>Se incluyeron un total de 2.033 estudios de 154 pa\u00edses o regiones que involucraron a 45.890.555 individuos. La prevalencia global de\u00a0obesidad infantil\u00a0fue del 8,5% (IC 95%, 8,2-8,8). Encontraron una variaci\u00f3n entre pa\u00edses, desde 0,4% (Vanuatu) hasta 28,4% (Puerto Rico). Se inform\u00f3 una mayor incidencia en aquellos con altos ingresos y puntuaciones de \u00edndice de desarrollo humano (IDH) de 0,8 o m\u00e1s. Entre 2012 y 2023, se observ\u00f3 un aumento de 1,5 veces en su prevalencia, en comparaci\u00f3n con el per\u00edodo de 2000 a 2011. Se identificaron diferencias sustanciales en las tasas de obesidad al estratificarlas por 11 factores de riesgo. La poblaci\u00f3n pedi\u00e1trica con obesidad ten\u00eda un alto riesgo de\u00a0depresi\u00f3n\u00a0e\u00a0hipertensi\u00f3n.<\/p>\n<p>En cuanto al sobrepeso, la incidencia fue del 14,8% (IC 95%, 14,5-15,1). Al realizar una estimaci\u00f3n combinada de sobrepeso y obesidad (exceso de peso), la prevalencia fue del 22,2% (IC 95%, 21,6-22,8).<\/p>\n<p>Los hallazgos de este estudio indican que aproximadamente uno de cada cinco ni\u00f1os o adolescentes presenta sobrepeso u obesidad, y que las tasas var\u00edan seg\u00fan el ingreso regional y el IDH. El\u00a0exceso de peso\u00a0se asocia con una combinaci\u00f3n de factores inherentes, conductuales, ambientales y socioculturales, que requieren la atenci\u00f3n e intervenci\u00f3n de profesionales de la salud, autoridades sanitarias y el p\u00fablico en general.<\/p>\n<p>Fuente: Diarioroat\u00e1n.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>06.09.2024 El\u00a0sobrepeso\u00a0y la\u00a0obesidad\u00a0en la infancia y la adolescencia representan un problema de salud global, asociado a consecuencias adversas a lo largo de la vida. Debido a esto, la Dra. Xinyue Zhang de la\u00a0Universidad de Sichuan\u00a0en China, junto con colaboradores de otras instituciones del pa\u00eds, estimaron la prevalencia mundial de sobrepeso y obesidad en ni\u00f1os y &hellip;<\/p>\n","protected":false},"author":0,"featured_media":78985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-79249","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-noticias"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/mickyandoniehn.com\/radio\/wp-content\/uploads\/2024\/09\/cnne-628214-uno-de-cada-cinco-ninos-sufre-obesidad-en-china-750x430-1-t52kwI.jpeg","_links":{"self":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/79249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/comments?post=79249"}],"version-history":[{"count":0,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/79249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media\/78985"}],"wp:attachment":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media?parent=79249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/categories?post=79249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/tags?post=79249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}