{"id":75626,"date":"2024-07-30T01:37:16","date_gmt":"2024-07-30T07:37:16","guid":{"rendered":"http:\/\/mickyandoniehn.com\/radio\/2024\/07\/30\/trump-promete-utilizar-el-bitcoin-como-reserva-nacional-estados-unidos-sera-la-capital-cripto-del-planeta\/"},"modified":"2024-07-30T01:37:16","modified_gmt":"2024-07-30T07:37:16","slug":"trump-promete-utilizar-el-bitcoin-como-reserva-nacional-estados-unidos-sera-la-capital-cripto-del-planeta","status":"publish","type":"post","link":"https:\/\/mickyandoniehn.com\/radio\/2024\/07\/30\/trump-promete-utilizar-el-bitcoin-como-reserva-nacional-estados-unidos-sera-la-capital-cripto-del-planeta\/","title":{"rendered":"Trump promete utilizar el Bitcoin como reserva nacional: \u00abEstados Unidos ser\u00e1 la capital cripto del planeta\u00bb"},"content":{"rendered":"<\/p>\n<p>La\u00a0<a href=\"https:\/\/x.com\/TheBitcoinConf\">conferencia Bitcoin 2024<\/a>\u00a0ha estado marcada por el discurso de Donald Trump. El candidato republicano ha aprovechado su intervenci\u00f3n para posicionarse como un claro defensor de las criptomonedas. Y ha ido m\u00e1s all\u00e1. Si resulta elegido,\u00a0<a href=\"https:\/\/www.cnbc.com\/2024\/07\/27\/trump-bitcoin-conference-harris.html\">ha prometido<\/a> que convertir\u00e1 Estados Unidos en \u00abla capital cripto del planeta\u00bb.<\/p>\n<p><strong>Reserva nacional estrat\u00e9gica de Bitcoin.\u00a0<\/strong>El discurso de Trump ha sido abiertamente en defensa de las criptomonedas, llegando a compararlas con sectores clave. \u00abSon como la industria del acero de hace 100 a\u00f1os, pero todav\u00eda est\u00e1n su infancia. Alg\u00fan d\u00eda probablemente superar\u00e1 al oro. Nunca ha habido nada parecido\u00bb, ha expresado.<\/p>\n<p>Trump ha defendido la idea de crear una \u00abreserva nacional estrat\u00e9gica de Bitcoin\u00bb con la promesa de \u00abnunca vender\u00bb, en una clara alusi\u00f3n al\u00a0<a href=\"https:\/\/www.xataka.com\/criptomonedas\/hodl-como-error-tipografico-acabo-siendo-uno-lemas-memes-populares-mundo-criptomonedas\">HODL<\/a>.<\/p>\n<p><strong>1 mill\u00f3n de BTC durante 20 a\u00f1os.\u00a0<\/strong>No ha sido Trump quien ha dado m\u00e1s detalles sobre esta idea, sino la senadora Cynthia Lummis. Su propuesta legislativa es que la reserva federal de los Estados Unidos re\u00fana un mill\u00f3n de bitcoins (unos 70.000 millones de d\u00f3lares al cambio actual) durante los pr\u00f3ximos cinco a\u00f1os.<\/p>\n<p>\u00abUna reserva que se mantendr\u00e1 durante al menos 20 a\u00f1os y solo podr\u00e1 utilizarse para un \u00fanico prop\u00f3sito: reducir la deuda\u00bb, defiende la senadora.<\/p>\n<p><strong>Bitcoins \u2018made in USA\u2019.\u00a0<\/strong>En su defensa, Trump ha explicado que \u00absi las criptomonedas van a marcar el futuro, deben minarse, acu\u00f1arse y producirse en Am\u00e9rica. Si el Bitcoin llegar\u00e1 a la Luna, como dicen, quiero que sea Am\u00e9rica quien lo env\u00ede all\u00ed\u00bb. A lo que ha a\u00f1adido que \u00absi no lo hacemos nosotros, lo har\u00e1 China\u00bb.<\/p>\n<p><strong>Derecho a la custodia propia.<\/strong>\u00a0Para favorecer estos bitcoins producidos en Estados Unidos, Trump ha defendido la implementaci\u00f3n del derecho a la custodia propia. Es decir, el candidato republicano expresa que intentar\u00e1 que el acceso a los\u00a0<a href=\"https:\/\/www.xataka.com\/criptomonedas\/panico-inversores-cripto-auge-monederos-frios-como-funcionan-cold-wallets\">monederos fr\u00edos<\/a>\u00a0est\u00e9 garantizado.<\/p>\n<p>\u00abNunca permitir\u00e9 la creaci\u00f3n de un Banco Central de Moneda Digital\u00bb, apunta Trump, en la direcci\u00f3n de que no habr\u00e1 un organismo superior que controle los bitcoins de los ciudadanos.<\/p>\n<p><strong>\u00abMake Bitcoin Great Again\u00bb.\u00a0<\/strong>Es uno de los esl\u00f3ganes que han aparecido entre los asistentes a la conferencia. \u00abLa represi\u00f3n de las criptomonedas y el bitcoin por parte del Gobierno Biden-Harris es err\u00f3nea y perjudicial para nuestro pa\u00eds\u00bb, expone Trump. En su lugar \u00e9l se presenta como el presidente de las criptomonedas. El que desregular\u00e1 el sector para inter\u00e9s de los inversores.<\/p>\n<p>Otro de los movimientos que ha defendido es el\u00a0<a href=\"https:\/\/x.com\/CollinRugg\/status\/1817298331355500999\">despido de Gary Gensler<\/a>, presidente de la Comisi\u00f3n de Bolsa y Valores (SEC) y\u00a0<a href=\"https:\/\/www.xataka.com\/criptomonedas\/sec-tiene-lista-su-regulacion-cripto-eeuu-hay-muchos-derrotados-claro-ganador\">uno de los encargados de la regulaci\u00f3n de las criptomonedas<\/a>\u00a0en Estados Unidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0conferencia Bitcoin 2024\u00a0ha estado marcada por el discurso de Donald Trump. El candidato republicano ha aprovechado su intervenci\u00f3n para posicionarse como un claro defensor de las criptomonedas. Y ha ido m\u00e1s all\u00e1. Si resulta elegido,\u00a0ha prometido que convertir\u00e1 Estados Unidos en \u00abla capital cripto del planeta\u00bb. Reserva nacional estrat\u00e9gica de Bitcoin.\u00a0El discurso de Trump ha &hellip;<\/p>\n","protected":false},"author":0,"featured_media":75627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-75626","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-noticias"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/mickyandoniehn.com\/radio\/wp-content\/uploads\/2024\/07\/500_333-XphnWA.jpeg","_links":{"self":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/75626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/comments?post=75626"}],"version-history":[{"count":0,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/75626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media\/75627"}],"wp:attachment":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media?parent=75626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/categories?post=75626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/tags?post=75626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}