{"id":68686,"date":"2024-03-07T07:12:36","date_gmt":"2024-03-07T13:12:36","guid":{"rendered":"https:\/\/mickyandoniehn.com\/radio\/2024\/03\/07\/honduras-en-la-historia-07-de-marzo-de-2015-se-crea-la-junta-administradora-de-agua-y-saneamiento-de-la-comunidad-de-san-lorenzo-municipio-de-tomala-departamento-de-lempira\/"},"modified":"2024-03-07T07:12:36","modified_gmt":"2024-03-07T13:12:36","slug":"honduras-en-la-historia-07-de-marzo-de-2015-se-crea-la-junta-administradora-de-agua-y-saneamiento-de-la-comunidad-de-san-lorenzo-municipio-de-tomala-departamento-de-lempira","status":"publish","type":"post","link":"https:\/\/mickyandoniehn.com\/radio\/2024\/03\/07\/honduras-en-la-historia-07-de-marzo-de-2015-se-crea-la-junta-administradora-de-agua-y-saneamiento-de-la-comunidad-de-san-lorenzo-municipio-de-tomala-departamento-de-lempira\/","title":{"rendered":"Honduras en la Historia: 07 de marzo de 2015, Se crea la Junta Administradora de Agua y Saneamiento de la Comunidad de San Lorenzo, Municipio de Tomal\u00e1, Departamento de Lempira"},"content":{"rendered":"<\/p>\n<p><strong>Honduras en la Historia: 07 de marzo de 2015, Se crea la Junta Administradora de Agua y Saneamiento de la Comunidad de San Lorenzo, Municipio de Tomal\u00e1, Departamento de Lempira<\/strong><\/p>\n<p><span>Conceder Personalidad Jur\u00eddica a la Organizaci\u00f3n denominada Junta Administradora de Agua y Saneamiento de La Comunidad de San Lorenzo, Municipio de Tomal\u00e1, Departamento de Lempira, con domicilio en la comunidad de San Lorenzo, municipio de Tomal\u00e1, departamento de Lempira; se aprueban sus estatutos en la forma siguiente:<\/span><\/p>\n<p><span><br \/>\nESTATUTOS DE LA JUNTA ADMINISTRADORA DE AGUA DE LA COMUNIDAD DE SAN LORENZO, MUNICIPIO DE TOMAL\u00c1, DEPARTAMENTO DE LEMPIRA<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Honduras en la Historia: 07 de marzo de 2015, Se crea la Junta Administradora de Agua y Saneamiento de la Comunidad de San Lorenzo, Municipio de Tomal\u00e1, Departamento de Lempira Conceder Personalidad Jur\u00eddica a la Organizaci\u00f3n denominada Junta Administradora de Agua y Saneamiento de La Comunidad de San Lorenzo, Municipio de Tomal\u00e1, Departamento de Lempira, &hellip;<\/p>\n","protected":false},"author":0,"featured_media":68687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-68686","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-noticias"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/mickyandoniehn.com\/radio\/wp-content\/uploads\/2024\/03\/Diapositiva1-3-UYMcHw.png","_links":{"self":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/68686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/comments?post=68686"}],"version-history":[{"count":0,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/68686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media\/68687"}],"wp:attachment":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media?parent=68686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/categories?post=68686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/tags?post=68686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}