{"id":51891,"date":"2023-03-04T10:12:45","date_gmt":"2023-03-04T16:12:45","guid":{"rendered":"https:\/\/mickyandoniehn.com\/radio\/2023\/03\/04\/le-suben-l40-a-caja-de-cartones-de-huevo-y-l1-a-medida-de-maiz\/"},"modified":"2023-03-04T10:12:45","modified_gmt":"2023-03-04T16:12:45","slug":"le-suben-l40-a-caja-de-cartones-de-huevo-y-l1-a-medida-de-maiz","status":"publish","type":"post","link":"https:\/\/mickyandoniehn.com\/radio\/2023\/03\/04\/le-suben-l40-a-caja-de-cartones-de-huevo-y-l1-a-medida-de-maiz\/","title":{"rendered":"Le suben L40 a caja de cartones de huevo y L1 a medida de ma\u00edz"},"content":{"rendered":"<\/p>\n<p><strong>Tegucigalpa. 04.03.2023<\/strong><\/p>\n<p>La docena de cartones de huevos, ma\u00edz, limones, pl\u00e1tanos, entre otros productos, subieron de precio en algunos mercados de la capital.<\/p>\n<p>En el zonal Bel\u00e9n aument\u00f3 la medida de ma\u00edz de 31 a 32 lempiras y la caja de huevos de 1,700 a 1,740 lempiras.<\/p>\n<p>El director de la Asociaci\u00f3n para la Defensa de la Canasta B\u00e1sica de Honduras (ADECABAH), Adalid Ir\u00edas, expres\u00f3 que en el zonal Bel\u00e9n ocho productos subieron de precio, entre estos, verduras y legumbres, como el lim\u00f3n, maracuy\u00e1, pl\u00e1tanos, zanahoria, chile verde y cebolla.<\/p>\n<p>Agreg\u00f3 que la medida de ma\u00edz \u201cesta semana sube de 31 lempiras a 32 lempiras, no obstante, que la carga se mantiene estable a 580 lempiras\u201d.<\/p>\n<div class=\"fs-dynamic\">\n<div class=\"up-show\">\n<div class=\"ahover\">\n<div class=\"upo-label\">AD<\/div>\n<\/div>\n<div>\n<div class=\"__fs-ancillary\">\n<div class=\"__fs-branding\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Ir\u00edas indic\u00f3 que \u201ctambi\u00e9n la caja de huevos de 12 cartones tuvo un incremento de 40 lempiras, pas\u00f3 de 1,700 a 1,740 lempiras de incremento, pero no se refleja el aumento en el cart\u00f3n de huevos porque esta semana se fija en 140 hasta 148 lempiras, mismos precios de la semana pasada\u201d.<\/p>\n<div class=\"lg:w-[748px] lg:mx-auto\"><\/div>\n<h3>CEBOLLAS Y ZAPALLOS<\/h3>\n<p>En relaci\u00f3n a la Feria del Agricultor y el Artesano, tres productos subieron de precio, entre estos la cebolla roja, que con un alza de 10 lempiras, pas\u00f3 a costar de 30 a 40 lempiras; los frijoles tiernos que se vend\u00edan a 16, ahora se cotizan a 18 lempiras, con un aumento de dos lempiras; mientras que el zapallo, con un aumento de tres lempiras, pas\u00f3 de siete a 10 lempiras.<\/p>\n<p>Pese a las alzas en menci\u00f3n, Ir\u00edas manifest\u00f3 que en el mercado zonal Bel\u00e9n y en la feria del estadio seis productos bajaron de precio.<\/p>\n<p>\u201cEn la feria del estadio la estabilidad es m\u00e1s notable porque solo suben apenas tres productos y seis productos bajaron, es decir, son m\u00e1s los que bajan que los que suben\u201d.<\/p>\n<div class=\"fs-dynamic\">\n<div class=\"up-show\">\n<div class=\"ahover\">\n<div class=\"upo-label\">AD<\/div>\n<\/div>\n<div>\n<div class=\"__fs-ancillary\">\n<div class=\"__fs-branding\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>\u201cEste fin de semana registramos una relativa estabilidad de precios, tanto en el zonal Bel\u00e9n como en la Feria del Agricultor y el Artesano debido a que pocos productos se fueron al alza\u201d.<\/p>\n<p>Ir\u00edas enfatiz\u00f3 que los l\u00e1cteos y las carnes se mantienen con el precio de la semana pasada y no tuvieron aumentos, de igual forma los mariscos.<\/p>\n<div class=\"lg:w-[748px] lg:mx-auto\"><\/div>\n<div><\/div>\n<div>Fuente: latribuna.hn<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tegucigalpa. 04.03.2023 La docena de cartones de huevos, ma\u00edz, limones, pl\u00e1tanos, entre otros productos, subieron de precio en algunos mercados de la capital. En el zonal Bel\u00e9n aument\u00f3 la medida de ma\u00edz de 31 a 32 lempiras y la caja de huevos de 1,700 a 1,740 lempiras. El director de la Asociaci\u00f3n para la Defensa &hellip;<\/p>\n","protected":false},"author":0,"featured_media":51892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-51891","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-noticias"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/mickyandoniehn.com\/radio\/wp-content\/uploads\/2023\/03\/FERIAS-1-txeoo1.jpeg","_links":{"self":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/51891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/comments?post=51891"}],"version-history":[{"count":0,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/51891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media\/51892"}],"wp:attachment":[{"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media?parent=51891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/categories?post=51891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/tags?post=51891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}