{"id":80707,"date":"2024-10-15T21:19:04","date_gmt":"2024-10-16T03:19:04","guid":{"rendered":"http:\/\/mickyandoniehn.com\/radio\/2024\/10\/15\/android-15-ya-esta-disponible-en-los-google-pixel-con-estas-novedades-es-cuestion-de-tiempo-que-aterrice-en-otros-fabricantes\/"},"modified":"2024-10-15T21:19:04","modified_gmt":"2024-10-16T03:19:04","slug":"android-15-ya-esta-disponible-en-los-google-pixel-con-estas-novedades-es-cuestion-de-tiempo-que-aterrice-en-otros-fabricantes","status":"publish","type":"post","link":"http:\/\/mickyandoniehn.com\/radio\/2024\/10\/15\/android-15-ya-esta-disponible-en-los-google-pixel-con-estas-novedades-es-cuestion-de-tiempo-que-aterrice-en-otros-fabricantes\/","title":{"rendered":"Android 15 ya est\u00e1 disponible en los Google Pixel con estas novedades: es cuesti\u00f3n de tiempo que aterrice en otros fabricantes"},"content":{"rendered":"<\/p>\n<p>La versi\u00f3n estable de\u00a0<a href=\"https:\/\/www.xataka.com\/nuevo\/nuevo-android-15-informacion\">Android 15<\/a>\u00a0comienza a estar disponible desde hoy para los propietarios de\u00a0<strong>dispositivos Pixel compatibles<\/strong>. Se trata de un despliegue algo at\u00edpico, ya que el fabricante chino\u00a0<a href=\"https:\/\/www.xataka.com\/moviles\/fabricante-chino-ha-logrado-impensable-adelantar-a-google-lanzando-android-15\">Vivo lanz\u00f3 este sistema operativo en su m\u00f3vil Fold 3 Pro el pasado mes de septiembre<\/a>, adelant\u00e1ndose a Google.<\/p>\n<div class=\"ad ad-lat\">\n<div class=\"ad-box\"><\/div>\n<\/div>\n<p>En cualquier caso,\u00a0<a href=\"https:\/\/blog.google\/products\/android\/android-15\/\">la llegada de Android 15 a los Pixel<\/a>\u00a0es un acontecimiento relevante, ya que allana el camino para su implementaci\u00f3n en dispositivos de otros fabricantes, incluidos aquellos que tienen acuerdos con la compa\u00f1\u00eda de Mountain View. Veamos cu\u00e1les son las novedades m\u00e1s destacadas de esta versi\u00f3n.<\/p>\n<h2>Las novedades m\u00e1s importantes de Android 15 \u2018Vanilla Ice Cream\u2019<\/h2>\n<p>Cuando hablamos de Android 15 estamos haciendo referencia a una versi\u00f3n del sistema operativo m\u00f3vil de Google que llega con una contenida cantidad de mejoras en relaci\u00f3n a\u00a0<a href=\"https:\/\/www.xataka.com\/nuevo\/android-14-informacion\">Android 14<\/a>.\u00a0<a href=\"https:\/\/www.xataka.com\/nuevo\/android-13-informacion\">Android 13<\/a>, por ejemplo, s\u00ed lleg\u00f3 con varios cambios notables, entre los que destacaba\u00a0<a href=\"https:\/\/www.xatakandroid.com\/sistema-operativo\/que-material-you-que-se-diferencia-material-design\">Material You<\/a>.<\/p>\n<p><strong>Detecci\u00f3n de robos y bloqueo autom\u00e1tico<\/strong>.\u00a0<a href=\"https:\/\/www.xataka.com\/aplicaciones\/robar-android-dejara-ser-goloso-nuevas-funciones-antirrobo-empiezan-a-desplegarse\">Como se\u00f1al\u00e1bamos a principios de este mes<\/a>, robar un Android dejar\u00e1 de ser tan goloso. Android 15 y algunas versiones anteriores ser\u00e1n capaces de detectar si un tel\u00e9fono ha sido arrebatado. La respuesta del sistema ser\u00e1 bloquear el dispositivo autom\u00e1ticamente.<\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"><\/div>\n<\/div>\n<p>Los usuarios tambi\u00e9n tendr\u00e1n la posibilidad de bloquear el m\u00f3vil manualmente de manera remota. Tan solo necesitar\u00e1n tener acceso a otro tel\u00e9fono y utilizar \u201csu tel\u00e9fono y una simple verificaci\u00f3n de seguridad\u201d para iniciar el proceso e impedir que el delincuente pueda utilizar el tel\u00e9fono robado.<\/p>\n<p><strong>Protecci\u00f3n adicional contra robos<\/strong>. Google ha prometido que Android 15 exigir\u00e1 que los usuarios se autentiquen para realizar ciertas configuraciones sospechosas, como eliminar una tarjeta SIM o desactivar Buscar mi dispositivo. El sistema bloquear\u00e1 el m\u00f3vil si detecta varios intentos fallidos en apps y ajustes.<\/p>\n<div class=\"ad ad-lat2\">\n<div class=\"ad-box\"><\/div>\n<\/div>\n<p><strong>Espacio privado<\/strong>. Android 15 ser\u00e1 m\u00e1s privado que nunca al permitir a los usuarios crear un \u201cespacio privado\u201d. El mismo ha sido dise\u00f1ado para las aplicaciones seleccionadas, como aplicaciones bancarias o de citas, permanezcan ocultas. Se podr\u00e1 acceder al espacio utilizando un m\u00e9todo de autenticaci\u00f3n.<\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"><\/div>\n<\/div>\n<p><strong>Barra de tareas vers\u00e1til<\/strong>. Aquellos usuarios que utilicen dispositivos plegables y tabletas podr\u00e1n anclar y desanclar la barra de tareas. La idea aqu\u00ed es que puedan tener un acceso m\u00e1s sencillo a sus aplicaciones. Tambi\u00e9n llegan atajos personalizables para abrir dos apps al mismo tiempo y as\u00ed facilitar la multitarea.<\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"><\/div>\n<\/div>\n<p><strong>Conectividad satelital<\/strong>. En m\u00f3viles compatibles y en determinadas regiones del mundo, las aplicaciones de mensajer\u00eda de los operadores podr\u00e1n utilizar una conexi\u00f3n satelital para enviar y recibir mensajes. Se trata de una funcionalidad ideal para seguir en contacto en zonas donde no hay cobertura m\u00f3vil.<\/p>\n<p>Mejores fotograf\u00edas. Los dispositivos Pixel estrenan Low Light Boost, una funcionalidad exclusiva que les permite tomar mejores fotograf\u00edas en condiciones de poca luz. Adem\u00e1s, en Android 15, las apps de c\u00e1mara de terceros tienen mayor control sobre el m\u00f3dulo de la c\u00e1mara, es decir, sensores y flash.<\/p>\n<div class=\"ad ad-lat\">\n<div class=\"ad-box\"><\/div>\n<\/div>\n<h2>Dispositivos Pixel compatibles con Android 15<\/h2>\n<p>Android 15 comenzar\u00e1 a estar disponible a partir de hoy, martes 15 de octubre, en los siguientes dispositivos Pixel.<\/p>\n<p><a href=\"https:\/\/www.xataka.com\/analisis\/google-pixel-6-analisis-caracteristicas-precio-especificaciones\">Google Pixel 6<\/a><br \/>\n<a href=\"https:\/\/www.xataka.com\/analisis\/google-pixel-6-pro-analisis-caracteristicas-precio-especificaciones\">Google Pixel 6 Pro<\/a><br \/>\n<a href=\"https:\/\/www.xataka.com\/analisis\/google-pixel-6a-analisis-caracteristicas-precio-especificaciones\">Google Pixel 6a<\/a><br \/>\n<a href=\"https:\/\/www.xataka.com\/analisis\/google-pixel-7-analisis-caracteristicas-precio-especificaciones\">Google Pixel 7<\/a><br \/>\n<a href=\"https:\/\/www.xataka.com\/analisis\/google-pixel-7-pro-analisis-caracteristicas-precio-especificaciones\">Google Pixel 7 Pro<\/a><br \/>\n<a href=\"https:\/\/www.xataka.com\/analisis\/google-pixel-7a-analisis-caracteristicas-precio-especificaciones\">Google Pixel 7a<\/a><br \/>\n<a href=\"https:\/\/www.xatakandroid.com\/moviles-android\/primer-vistazo-al-pixel-fold-plegable-google-que-conoceremos-google-i-2023\">Google Pixel Fold<\/a><br \/>\n<a href=\"https:\/\/www.xatakandroid.com\/gadgets-android\/google-pixel-tablet-caracteristicas-precio-ficha-tecnica\">Google Pixel Tablet<\/a><br \/>\n<a href=\"https:\/\/www.xatakandroid.com\/moviles-android\/google-pixel-8-caracteristicas-precio-ficha-tecnica\">Google Pixel 8<\/a><br \/>\n<a href=\"https:\/\/www.xataka.com\/analisis\/google-pixel-8-pro-analisis-caracteristicas-precio-especificaciones\">Google Pixel 8 Pro<\/a><br \/>\n<a href=\"https:\/\/www.xatakandroid.com\/moviles-android\/google-pixel-8a-caracteristicas-precio-ficha-tecnica\">Google Pixel 8a<\/a><br \/>\n<a href=\"https:\/\/www.xataka.com\/moviles\/google-pixel-9-caracteristicas-precio-ficha-tecnica\">Pixel 9<\/a><br \/>\n<a href=\"https:\/\/www.xataka.com\/analisis\/google-pixel-9-pro-analisis-caracteristicas-precio-especificaciones\">Pixel 9 Pro<\/a><br \/>\n<a href=\"https:\/\/www.xataka.com\/analisis\/google-pixel-9-pro-xl-analisis-caracteristicas-precio-especificaciones\">Pixel 9 Pro XL<\/a><br \/>\n<a href=\"https:\/\/www.xataka.com\/moviles\/google-pixel-9-pro-fold-caracteristicas-precio-ficha-tecnica\">Pixel 9 Pro Fold<\/a><\/p>\n<p>Para actualizar tan solo tienes que entrar en\u00a0<em>Configuraci\u00f3n<\/em>\u00a0&gt;\u00a0<em>Sistema<\/em>\u00a0&gt;\u00a0<em>Actualizaci\u00f3n del sistema<\/em>\u00a0y pulsar sobre \u201cBuscar actualizaciones\u201d. Si la actualizaci\u00f3n todav\u00eda no aparece, tendr\u00e1s que esperar un poco y volver a intentarlo.<\/p>\n<h2>\u00bfCu\u00e1nto llegar\u00e1 Android 15 al resto de los fabricantes?<\/h2>\n<p>Es cuesti\u00f3n de tiempo que Android 15 llegue a otros fabricantes. Google ha dicho que estar\u00e1 disponible \u201cen los pr\u00f3ximos meses\u201d en marcas como Samsung, Honor, iQOO, Lenovo, Motorola, Nothing, OnePlus, Oppo, realme, Sharp, Sony, Tecno y Xiaomi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La versi\u00f3n estable de\u00a0Android 15\u00a0comienza a estar disponible desde hoy para los propietarios de\u00a0dispositivos Pixel compatibles. Se trata de un despliegue algo at\u00edpico, ya que el fabricante chino\u00a0Vivo lanz\u00f3 este sistema operativo en su m\u00f3vil Fold 3 Pro el pasado mes de septiembre, adelant\u00e1ndose a Google. En cualquier caso,\u00a0la llegada de Android 15 a los &hellip;<\/p>\n","protected":false},"author":0,"featured_media":80708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-80707","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-noticias"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"http:\/\/mickyandoniehn.com\/radio\/wp-content\/uploads\/2024\/10\/500_333-sy5x8W.jpeg","_links":{"self":[{"href":"http:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/80707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/comments?post=80707"}],"version-history":[{"count":0,"href":"http:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/posts\/80707\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media\/80708"}],"wp:attachment":[{"href":"http:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/media?parent=80707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/categories?post=80707"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/mickyandoniehn.com\/radio\/wp-json\/wp\/v2\/tags?post=80707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}